{"id":31,"count":17,"description":"Conseils et guides pas \u00e0 pas pour pr\u00e9parer votre voyage en Am\u00e9rique Centrale : quand partir, visa, vaccins, location de voiture, budget, climat, et toutes les informations pratiques.","link":"https:\/\/toucandiscovery.com\/de\/category\/guides-pratiques\/","name":"Praktische Leitf\u00e4den","slug":"guides-pratiques","taxonomy":"category","parent":0,"meta":[],"z_taxonomy_image_url":"https:\/\/toucandiscovery.com\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","acf":[],"_links":{"self":[{"href":"https:\/\/toucandiscovery.com\/de\/wp-json\/wp\/v2\/categories\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toucandiscovery.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/toucandiscovery.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/toucandiscovery.com\/de\/wp-json\/wp\/v2\/posts?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}