{"id":4534,"date":"2026-04-23T19:47:56","date_gmt":"2026-04-23T19:47:56","guid":{"rendered":"https:\/\/toucandiscovery.com\/?page_id=4534"},"modified":"2026-04-29T03:59:59","modified_gmt":"2026-04-29T03:59:59","slug":"conditions-generales-de-vente","status":"publish","type":"page","link":"https:\/\/toucandiscovery.com\/it\/conditions-generales-de-vente\/","title":{"rendered":"Termini e condizioni di vendita"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4534\" class=\"elementor elementor-4534\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f95e26a e-flex e-con-boxed e-con e-parent\" data-id=\"f95e26a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;grandtour_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;grandtour_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;grandtour_ext_is_background_on_scroll&quot;:&quot;false&quot;,&quot;grandtour_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;grandtour_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;grandtour_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;grandtour_ext_is_sticky&quot;:&quot;false&quot;,&quot;grandtour_ext_is_scrollme&quot;:&quot;false&quot;,&quot;grandtour_ext_is_smoove&quot;:&quot;false&quot;,&quot;grandtour_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;grandtour_ext_is_infinite&quot;:&quot;false&quot;,&quot;grandtour_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;grandtour_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9e2b41 elementor-widget elementor-widget-html\" data-id=\"a9e2b41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;grandtour_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;grandtour_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;grandtour_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;grandtour_ext_is_sticky&quot;:&quot;false&quot;,&quot;grandtour_ext_is_scrollme&quot;:&quot;false&quot;,&quot;grandtour_ext_is_smoove&quot;:&quot;false&quot;,&quot;grandtour_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;grandtour_ext_is_infinite&quot;:&quot;false&quot;,&quot;grandtour_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;grandtour_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!-- ============================================================\r\n     TOUCAN DISCOVERY \u2014 Conditions G\u00e9n\u00e9rales de Vente (HTML custom)\r\n     Version : 2.0 FINALE \u00b7 23 avril 2026\r\n     ============================================================\r\n     VERSION DEFINITIVE \u2014 toutes valeurs renseignees, aucun placeholder.\r\n     Param\u00e8tres int\u00e9gr\u00e9s :\r\n     - Soci\u00e9t\u00e9 : Toucan Discovery S.R.L. (C\u00e9dula 3-102-862013)\r\n     - Cr\u00e9ation : 2023\r\n     - Devise : USD uniquement\r\n     - Acompte : 30% \u00e0 la confirmation\r\n     - Solde : 30 jours avant d\u00e9part\r\n     - Bar\u00e8me annulation (Toucan prot\u00e9g\u00e9) :\r\n         * > 60 jours : 25%\r\n         * 60-30 jours : 50%\r\n         * 30-15 jours : 75%\r\n         * < 15 jours \/ no-show : 100%\r\n     - Paiement : virement SWIFT + carte bancaire via lien de paiement s\u00e9curis\u00e9\r\n     - Frais modification : 50 USD\r\n     - D\u00e9lai r\u00e9clamation post-retour : 30 jours\r\n     - Validit\u00e9 des devis : 15 jours\r\n     - Assurance partenaire recommand\u00e9e : Chapka\r\n     - Assistance 24\/7 : +506 8777-7166\r\n\r\n     MODE D'EMPLOI :\r\n     1. WordPress \u2192 Pages \u2192 Ajouter nouvelle \u2192 titre \"Conditions G\u00e9n\u00e9rales de Vente\"\r\n        \u2192 Mod\u00e8le : Elementor Canvas \u2192 Publier\r\n     2. Modifier avec Elementor \u2192 widget HTML \u2192 coller TOUT le contenu\r\n        ci-dessous (du <style> \u00e0 la fin du <\/div>) \u2192 Publier\r\n     ============================================================ -->\r\n\r\n<style>\r\n\/* Styles scoped *\/\r\n.td-page-legal {\r\n  font-family: 'Montserrat', Arial, sans-serif;\r\n  color: #1B2A5A;\r\n  line-height: 1.6;\r\n  font-size: 16px;\r\n}\r\n.td-page-legal * { box-sizing: border-box; }\r\n.td-page-legal a { color: #F7941D; text-decoration: none; transition: color 0.2s; }\r\n.td-page-legal a:hover { color: #7DC242; text-decoration: underline; }\r\n\r\n\/* Hero *\/\r\n.td-page-legal .tdl-hero {\r\n  background: linear-gradient(135deg, #1B2A5A 0%, #17365D 100%);\r\n  color: #FFFFFF;\r\n  padding: 4rem 1.5rem 3rem;\r\n  text-align: center;\r\n}\r\n.td-page-legal .tdl-hero h1 {\r\n  font-family: 'Montserrat', Arial, sans-serif;\r\n  font-weight: 800;\r\n  font-size: clamp(2rem, 5vw, 3.5rem);\r\n  margin: 0 0 0.5rem;\r\n  color: #FFFFFF;\r\n  line-height: 1.1;\r\n}\r\n.td-page-legal .tdl-hero p { margin: 0; opacity: 0.9; font-size: 1rem; }\r\n.td-page-legal .tdl-hero .tdl-accent {\r\n  display: inline-block;\r\n  width: 60px;\r\n  height: 3px;\r\n  background: #7DC242;\r\n  margin: 1rem auto 0;\r\n}\r\n\r\n\/* Breadcrumb *\/\r\n.td-page-legal .tdl-breadcrumb {\r\n  max-width: 1200px;\r\n  margin: 0 auto;\r\n  padding: 1rem 1.5rem;\r\n  font-size: 0.875rem;\r\n  color: #666666;\r\n}\r\n.td-page-legal .tdl-breadcrumb a { color: #666666; }\r\n.td-page-legal .tdl-breadcrumb a:hover { color: #F7941D; }\r\n.td-page-legal .tdl-breadcrumb span.sep { margin: 0 0.5rem; opacity: 0.5; }\r\n\r\n\/* Sommaire *\/\r\n.td-page-legal .tdl-toc {\r\n  max-width: 760px;\r\n  margin: 2rem auto 0;\r\n  padding: 1.5rem;\r\n  background: #F5F5F5;\r\n  border-radius: 8px;\r\n}\r\n.td-page-legal .tdl-toc h2 {\r\n  font-size: 1rem;\r\n  font-weight: 700;\r\n  margin: 0 0 0.75rem;\r\n  color: #17365D;\r\n  text-transform: uppercase;\r\n  letter-spacing: 0.05em;\r\n}\r\n.td-page-legal .tdl-toc ol {\r\n  margin: 0;\r\n  padding-left: 1.25rem;\r\n  columns: 2;\r\n  column-gap: 2rem;\r\n  font-size: 0.875rem;\r\n}\r\n.td-page-legal .tdl-toc ol li {\r\n  margin-bottom: 0.35rem;\r\n  break-inside: avoid;\r\n}\r\n.td-page-legal .tdl-toc a { color: #1B2A5A; text-decoration: none; }\r\n.td-page-legal .tdl-toc a:hover { color: #F7941D; }\r\n\r\n@media (max-width: 600px) {\r\n  .td-page-legal .tdl-toc ol { columns: 1; }\r\n}\r\n\r\n\/* Contenu *\/\r\n.td-page-legal .tdl-content {\r\n  max-width: 760px;\r\n  margin: 0 auto;\r\n  padding: 2rem 1.5rem 4rem;\r\n}\r\n.td-page-legal .tdl-content h2 {\r\n  font-family: 'Montserrat', Arial, sans-serif;\r\n  font-size: 1.5rem;\r\n  font-weight: 700;\r\n  color: #1B2A5A;\r\n  margin: 2.5rem 0 1rem;\r\n  padding-bottom: 0.5rem;\r\n  border-bottom: 2px solid #7DC242;\r\n  scroll-margin-top: 2rem;\r\n}\r\n.td-page-legal .tdl-content h2:first-of-type { margin-top: 0; }\r\n.td-page-legal .tdl-content h3 {\r\n  font-size: 1.125rem;\r\n  font-weight: 600;\r\n  color: #17365D;\r\n  margin: 1.5rem 0 0.5rem;\r\n}\r\n.td-page-legal .tdl-content p { margin: 0 0 1rem; }\r\n.td-page-legal .tdl-content ul, .td-page-legal .tdl-content ol {\r\n  padding-left: 1.25rem;\r\n  margin: 0 0 1rem;\r\n}\r\n.td-page-legal .tdl-content li { margin-bottom: 0.5rem; }\r\n.td-page-legal .tdl-content strong { color: #1B2A5A; }\r\n\r\n\/* Info *\/\r\n.td-page-legal .tdl-info {\r\n  background: #F5F5F5;\r\n  border-left: 4px solid #7DC242;\r\n  padding: 1.25rem 1.5rem;\r\n  margin: 1.5rem 0;\r\n  border-radius: 4px;\r\n}\r\n.td-page-legal .tdl-info p { margin: 0 0 0.5rem; }\r\n.td-page-legal .tdl-info p:last-child { margin-bottom: 0; }\r\n\r\n\/* Alert orange *\/\r\n.td-page-legal .tdl-alert {\r\n  background: #FFF7ED;\r\n  border-left: 4px solid #F7941D;\r\n  padding: 1.25rem 1.5rem;\r\n  margin: 1.5rem 0;\r\n  border-radius: 4px;\r\n}\r\n.td-page-legal .tdl-alert p { margin: 0; }\r\n.td-page-legal .tdl-alert strong { color: #F7941D; }\r\n\r\n\/* Tableau bar\u00e8me annulation *\/\r\n.td-page-legal .tdl-table {\r\n  width: 100%;\r\n  border-collapse: collapse;\r\n  margin: 1rem 0 1.5rem;\r\n  font-size: 0.9rem;\r\n  border-radius: 8px;\r\n  overflow: hidden;\r\n  box-shadow: 0 2px 8px rgba(27, 42, 90, 0.08);\r\n}\r\n.td-page-legal .tdl-table th {\r\n  background: #17365D;\r\n  color: #FFFFFF;\r\n  font-weight: 600;\r\n  padding: 0.75rem 1rem;\r\n  text-align: left;\r\n  font-size: 0.85rem;\r\n  text-transform: uppercase;\r\n  letter-spacing: 0.03em;\r\n}\r\n.td-page-legal .tdl-table td {\r\n  padding: 0.75rem 1rem;\r\n  border-bottom: 1px solid #E8E8E8;\r\n  vertical-align: top;\r\n}\r\n.td-page-legal .tdl-table tr:nth-child(even) td { background: #F5F5F5; }\r\n.td-page-legal .tdl-table tr:last-child td { border-bottom: none; }\r\n.td-page-legal .tdl-table td.fee { font-weight: 700; color: #F7941D; }\r\n\r\n\/* CTA *\/\r\n.td-page-legal .tdl-cta {\r\n  background: linear-gradient(135deg, #7DC242 0%, #3A7D34 100%);\r\n  color: #FFFFFF;\r\n  padding: 3rem 1.5rem;\r\n  text-align: center;\r\n  border-radius: 16px;\r\n  margin: 3rem auto;\r\n  max-width: 1140px;\r\n}\r\n.td-page-legal .tdl-cta h2 {\r\n  color: #FFFFFF;\r\n  font-size: clamp(1.5rem, 3vw, 2rem);\r\n  margin: 0 0 0.75rem;\r\n  border: none;\r\n}\r\n.td-page-legal .tdl-cta p { margin: 0 0 1.5rem; opacity: 0.95; }\r\n.td-page-legal .tdl-cta .tdl-btn {\r\n  display: inline-block;\r\n  padding: 0.875rem 2rem;\r\n  background: #F7941D;\r\n  color: #FFFFFF;\r\n  text-decoration: none;\r\n  border-radius: 8px;\r\n  font-weight: 600;\r\n  font-size: 1rem;\r\n  transition: all 0.2s;\r\n}\r\n.td-page-legal .tdl-cta .tdl-btn:hover {\r\n  background: #d87a0f;\r\n  transform: translateY(-2px);\r\n  box-shadow: 0 8px 24px rgba(0,0,0,0.2);\r\n  color: #FFFFFF;\r\n  text-decoration: none;\r\n}\r\n\r\n@media (max-width: 600px) {\r\n  .td-page-legal .tdl-hero { padding: 3rem 1rem 2rem; }\r\n  .td-page-legal .tdl-content { padding: 1.5rem 1rem 3rem; }\r\n  .td-page-legal .tdl-cta { padding: 2rem 1rem; border-radius: 8px; }\r\n  .td-page-legal .tdl-table { font-size: 0.8rem; }\r\n  .td-page-legal .tdl-table th, .td-page-legal .tdl-table td { padding: 0.5rem; }\r\n}\r\n<\/style>\r\n\r\n<div class=\"td-page-legal\">\r\n\r\n  <!-- Hero -->\r\n  <header class=\"tdl-hero\">\r\n    <h1>Termini e condizioni di vendita<\/h1>\r\n    <p>Derni\u00e8re mise \u00e0 jour : 23 avril 2026<\/p>\r\n    <div class=\"tdl-accent\"><\/div>\r\n  <\/header>\r\n\r\n  <!-- Breadcrumb -->\r\n  <nav class=\"tdl-breadcrumb\" aria-label=\"Fil d'Ariane\">\r\n    <a href=\"\/it\/\">Casa<\/a>\r\n    <span class=\"sep\">\u203a<\/span>\r\n    <span>Termini e condizioni di vendita<\/span>\r\n  <\/nav>\r\n\r\n  <!-- Sommaire -->\r\n  <aside class=\"tdl-toc\" aria-label=\"Contenuti\">\r\n    <h2>Contenuti<\/h2>\r\n    <ol>\r\n      <li><a href=\"#definitions\">D\u00e9finitions<\/a><\/li>\r\n      <li><a href=\"#acceptation\">Acceptation<\/a><\/li>\r\n      <li><a href=\"#objet\">Objet<\/a><\/li>\r\n      <li><a href=\"#reservation\">Processus de r\u00e9servation<\/a><\/li>\r\n      <li><a href=\"#prix-paiement\">Prix et paiement<\/a><\/li>\r\n      <li><a href=\"#annulation-client\">Annulation par le client<\/a><\/li>\r\n      <li><a href=\"#modification-client\">Modification par le client<\/a><\/li>\r\n      <li><a href=\"#annulation-toucan\">Annulation par Toucan<\/a><\/li>\r\n      <li><a href=\"#force-majeure\">Force majeure<\/a><\/li>\r\n      <li><a href=\"#responsabilite\">Responsabilit\u00e9 et assurance<\/a><\/li>\r\n      <li><a href=\"#documents\">Documents de voyage<\/a><\/li>\r\n      <li><a href=\"#reclamations\">R\u00e9clamations<\/a><\/li>\r\n      <li><a href=\"#donnees\">Donn\u00e9es personnelles<\/a><\/li>\r\n      <li><a href=\"#juridiction\">Droit applicable et juridiction<\/a><\/li>\r\n      <li><a href=\"#contact\">Contatto<\/a><\/li>\r\n    <\/ol>\r\n  <\/aside>\r\n\r\n  <!-- Contenu -->\r\n  <main class=\"tdl-content\">\r\n\r\n    <h2 id=\"definitions\">1. D\u00e9finitions<\/h2>\r\n    <p>Dans les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente (ci-apr\u00e8s \"CGV\") :<\/p>\r\n    <ul>\r\n      <li><strong>\"Toucan Discovery\"<\/strong> o <strong>\"Nous\"<\/strong> d\u00e9signe la soci\u00e9t\u00e9 Toucan Discovery S.R.L., agence de voyages r\u00e9ceptive (Destination Management Company) enregistr\u00e9e au Costa Rica sous la C\u00e9dula Jur\u00eddica 3-102-862013, organisatrice des prestations propos\u00e9es.<\/li>\r\n      <li><strong>\"Client\"<\/strong> o <strong>\"Vous\"<\/strong> d\u00e9signe toute personne physique ou morale (agence de voyages, tour-op\u00e9rateur, voyageur individuel) r\u00e9servant une prestation aupr\u00e8s de Toucan Discovery.<\/li>\r\n      <li><strong>\"Prestation\"<\/strong> d\u00e9signe tout service fourni par Toucan Discovery : programme de voyage sur mesure, circuit, transfert, h\u00e9bergement, activit\u00e9, guide, ou tout autre service touristique.<\/li>\r\n      <li><strong>\"Voyageurs\"<\/strong> d\u00e9signe les personnes effectivement inscrites \u00e0 la Prestation.<\/li>\r\n      <li><strong>\"Devis\"<\/strong> d\u00e9signe l'offre commerciale d\u00e9taill\u00e9e envoy\u00e9e au Client, incluant prix, prestations incluses et exclusions.<\/li>\r\n    <\/ul>\r\n\r\n    <h2 id=\"acceptation\">2. Acceptation des CGV<\/h2>\r\n    <p>\r\n      Toute r\u00e9servation aupr\u00e8s de Toucan Discovery implique l'acceptation sans r\u00e9serve des pr\u00e9sentes\r\n      CGV par le Client. Ces CGV pr\u00e9valent sur toute autre condition, sauf d\u00e9rogation expresse\r\n      \u00e9crite accept\u00e9e par Toucan Discovery.\r\n    <\/p>\r\n    <p>\r\n      Toucan Discovery se r\u00e9serve le droit de modifier \u00e0 tout moment les pr\u00e9sentes CGV. Les\r\n      conditions applicables sont celles en vigueur \u00e0 la date de confirmation de la r\u00e9servation.\r\n    <\/p>\r\n\r\n    <h2 id=\"objet\">3. Objet<\/h2>\r\n    <p>\r\n      Les pr\u00e9sentes CGV r\u00e9gissent les relations contractuelles entre Toucan Discovery et ses\r\n      Clients concernant la vente de services touristiques au Costa Rica, au Panama, au Nicaragua\r\n      et dans les autres destinations d'Am\u00e9rique centrale et des Cara\u00efbes propos\u00e9es par\r\n      Toucan Discovery.\r\n    <\/p>\r\n    <p>\r\n      Toucan Discovery, fond\u00e9e en 2023, agit en qualit\u00e9 d'organisateur et\/ou de revendeur de\r\n      prestations touristiques conform\u00e9ment \u00e0 la r\u00e9glementation costaricaine applicable aux\r\n      agences de voyages r\u00e9ceptives.\r\n    <\/p>\r\n\r\n    <h2 id=\"reservation\">4. Processus de r\u00e9servation<\/h2>\r\n\r\n    <h3>4.1 Demande de devis<\/h3>\r\n    <p>\r\n      Toute demande de voyage fait l'objet d'un Devis d\u00e9taill\u00e9 gratuit. Le Devis pr\u00e9cise les\r\n      prestations incluses, les exclusions, les dates, le prix total et la dur\u00e9e de validit\u00e9 de l'offre.\r\n    <\/p>\r\n    <p>\r\n      <strong>Validit\u00e9 des devis :<\/strong> sauf mention contraire indiqu\u00e9e sur l'offre, les devis\r\n      \u00e9mis par Toucan Discovery sont valables 15 jours calendaires \u00e0 compter de leur date d'\u00e9mission.\r\n      Pass\u00e9 ce d\u00e9lai, les tarifs et disponibilit\u00e9s peuvent avoir \u00e9volu\u00e9 et un nouveau devis devra\r\n      \u00eatre sollicit\u00e9.\r\n    <\/p>\r\n\r\n    <h3>4.2 Confirmation de r\u00e9servation<\/h3>\r\n    <p>La r\u00e9servation est consid\u00e9r\u00e9e comme ferme et d\u00e9finitive apr\u00e8s :<\/p>\r\n    <ol>\r\n      <li>L'acceptation \u00e9crite du Devis par le Client (email suffisant) ;<\/li>\r\n      <li>Le versement de l'acompte dans les conditions pr\u00e9vues \u00e0 l'article 5 ;<\/li>\r\n      <li>L'envoi par Toucan Discovery de la confirmation de r\u00e9servation.<\/li>\r\n    <\/ol>\r\n    <p>\r\n      Les disponibilit\u00e9s h\u00f4teli\u00e8res et a\u00e9riennes n'\u00e9tant pas garanties tant que la r\u00e9servation n'est\r\n      pas confirm\u00e9e, Toucan Discovery ne pourra \u00eatre tenu responsable d'une augmentation tarifaire\r\n      ou d'une indisponibilit\u00e9 survenant entre l'\u00e9mission du Devis et sa confirmation.\r\n    <\/p>\r\n\r\n    <h2 id=\"prix-paiement\">5. Prix et conditions de paiement<\/h2>\r\n\r\n    <h3>5.1 Prix<\/h3>\r\n    <p>\r\n      Les prix sont exprim\u00e9s en <strong>dollars am\u00e9ricains (USD)<\/strong>. Ils incluent les\r\n      prestations list\u00e9es dans le Devis et excluent tout service non mentionn\u00e9 (vols\r\n      internationaux, assurances personnelles, pourboires, d\u00e9penses personnelles, boissons hors\r\n      repas inclus, etc.).\r\n    <\/p>\r\n    <p>\r\n      Toucan Discovery se r\u00e9serve le droit d'ajuster le prix en cas de :\r\n    <\/p>\r\n    <ul>\r\n      <li>Modification du nombre de voyageurs ou de la dur\u00e9e du s\u00e9jour ;<\/li>\r\n      <li>Variation significative du taux de change entre la date du Devis et la date de confirmation ;<\/li>\r\n      <li>Augmentation impos\u00e9e par un fournisseur ind\u00e9pendante de la volont\u00e9 de Toucan Discovery.<\/li>\r\n    <\/ul>\r\n\r\n    <h3>5.2 Modalit\u00e9s de paiement<\/h3>\r\n    <div class=\"tdl-info\">\r\n      <p><strong>Acompte :<\/strong> 30% du montant total \u00e0 la confirmation de la r\u00e9servation<\/p>\r\n      <p><strong>Solde :<\/strong> au plus tard 30 jours calendaires avant la date de d\u00e9part<\/p>\r\n      <p><strong>R\u00e9servation \u00e0 moins de 30 jours du d\u00e9part :<\/strong> paiement int\u00e9gral \u00e0 la confirmation<\/p>\r\n    <\/div>\r\n\r\n    <h3>5.3 Moyens de paiement accept\u00e9s<\/h3>\r\n    <ul>\r\n      <li><strong>Virement bancaire international (SWIFT)<\/strong> sur notre compte professionnel costaricain. Les coordonn\u00e9es bancaires compl\u00e8tes (IBAN, SWIFT\/BIC, b\u00e9n\u00e9ficiaire) sont communiqu\u00e9es sur la facture pro forma accompagnant la confirmation de r\u00e9servation.<\/li>\r\n      <li><strong>Carte bancaire<\/strong> via un lien de paiement s\u00e9curis\u00e9 envoy\u00e9 par email. Toutes les principales cartes sont accept\u00e9es (Visa, Mastercard, American Express selon disponibilit\u00e9). Les transactions sont trait\u00e9es par un prestataire de paiement tiers certifi\u00e9 PCI-DSS.<\/li>\r\n    <\/ul>\r\n    <p>\r\n      Les \u00e9ventuels frais bancaires (virements internationaux, commissions carte, conversion de\r\n      devise pour les paiements hors USD) sont \u00e0 la charge du Client. Toucan Discovery ne per\u00e7oit\r\n      aucune commission suppl\u00e9mentaire sur les modes de paiement propos\u00e9s.\r\n    <\/p>\r\n\r\n    <h3>5.4 Retard de paiement<\/h3>\r\n    <p>\r\n      En cas de non-paiement du solde \u00e0 la date convenue, Toucan Discovery se r\u00e9serve le droit,\r\n      apr\u00e8s mise en demeure rest\u00e9e sans effet sous 48 heures, d'annuler la r\u00e9servation sans\r\n      remboursement de l'acompte et d'appliquer les conditions d'annulation pr\u00e9vues \u00e0 l'article 6.\r\n    <\/p>\r\n\r\n    <h2 id=\"annulation-client\">6. Conditions d'annulation par le Client<\/h2>\r\n    <p>\r\n      Toute annulation de r\u00e9servation doit \u00eatre notifi\u00e9e par \u00e9crit (email \u00e0\r\n      <a href=\"mailto:admin@toucandiscovery.com\">admin@toucandiscovery.com<\/a>) et prend effet \u00e0 la\r\n      date de r\u00e9ception. Les frais d'annulation suivants s'appliquent :\r\n    <\/p>\r\n\r\n    <table class=\"tdl-table\">\r\n      <thead>\r\n        <tr>\r\n          <th>D\u00e9lai avant d\u00e9part<\/th>\r\n          <th>Frais retenus<\/th>\r\n        <\/tr>\r\n      <\/thead>\r\n      <tbody>\r\n        <tr>\r\n          <td>Plus de 60 jours<\/td>\r\n          <td class=\"fee\">25% du montant total<\/td>\r\n        <\/tr>\r\n        <tr>\r\n          <td>Entre 60 et 30 jours<\/td>\r\n          <td class=\"fee\">50%<\/td>\r\n        <\/tr>\r\n        <tr>\r\n          <td>Entre 30 et 15 jours<\/td>\r\n          <td class=\"fee\">75%<\/td>\r\n        <\/tr>\r\n        <tr>\r\n          <td>Moins de 15 jours \/ no-show<\/td>\r\n          <td class=\"fee\">100%<\/td>\r\n        <\/tr>\r\n      <\/tbody>\r\n    <\/table>\r\n\r\n    <div class=\"tdl-alert\">\r\n      <p><strong>Important :<\/strong> certains services (h\u00f4tels non remboursables, vols internes, activit\u00e9s sp\u00e9cifiques comme la plong\u00e9e ou les vols en h\u00e9licopt\u00e8re) peuvent faire l'objet de conditions d'annulation plus strictes impos\u00e9es directement par nos fournisseurs. Ces conditions particuli\u00e8res sont pr\u00e9cis\u00e9es au moment du Devis et priment alors sur le bar\u00e8me ci-dessus pour les prestations concern\u00e9es.<\/p>\r\n    <\/div>\r\n\r\n    <h2 id=\"modification-client\">7. Modification par le Client<\/h2>\r\n    <p>\r\n      Toute demande de modification post\u00e9rieure \u00e0 la confirmation (dates, nombre de voyageurs,\r\n      prestations) fait l'objet d'une \u00e9tude par Toucan Discovery.\r\n    <\/p>\r\n    <p>Les modifications sont soumises \u00e0 :<\/p>\r\n    <ul>\r\n      <li>La disponibilit\u00e9 des prestations demand\u00e9es ;<\/li>\r\n      <li>L'acceptation par les fournisseurs concern\u00e9s ;<\/li>\r\n      <li>Des frais administratifs forfaitaires de <strong>50 USD par modification<\/strong> ;<\/li>\r\n      <li>Toute diff\u00e9rence tarifaire li\u00e9e \u00e0 la modification.<\/li>\r\n    <\/ul>\r\n    <p>\r\n      Toute modification majeure (changement de dates de plus de 7 jours, annulation de plus de\r\n      20% des voyageurs) peut \u00eatre assimil\u00e9e \u00e0 une annulation et soumise aux conditions de\r\n      l'article 6.\r\n    <\/p>\r\n\r\n    <h2 id=\"annulation-toucan\">8. Annulation ou modification par Toucan Discovery<\/h2>\r\n    <p>\r\n      Toucan Discovery se r\u00e9serve le droit d'annuler ou de modifier une Prestation dans les cas\r\n      suivants :\r\n    <\/p>\r\n    <ul>\r\n      <li>Nombre minimum de participants non atteint (pour les circuits de groupe) ;<\/li>\r\n      <li>Circonstances exceptionnelles ind\u00e9pendantes de notre volont\u00e9 ;<\/li>\r\n      <li>Force majeure (voir article 9).<\/li>\r\n    <\/ul>\r\n    <p>Dans ces cas, le Client sera inform\u00e9 dans les meilleurs d\u00e9lais et se verra proposer :<\/p>\r\n    <ol>\r\n      <li>Une prestation \u00e9quivalente de qualit\u00e9 similaire, ou<\/li>\r\n      <li>Le remboursement int\u00e9gral des sommes vers\u00e9es.<\/li>\r\n    <\/ol>\r\n    <p>\r\n      Aucune indemnisation compl\u00e9mentaire ne pourra \u00eatre r\u00e9clam\u00e9e au-del\u00e0 du remboursement des\r\n      sommes vers\u00e9es, sauf faute prouv\u00e9e de Toucan Discovery.\r\n    <\/p>\r\n\r\n    <h2 id=\"force-majeure\">9. Force majeure<\/h2>\r\n    <p>Sont consid\u00e9r\u00e9s comme cas de force majeure les \u00e9v\u00e9nements ext\u00e9rieurs, impr\u00e9visibles et irr\u00e9sistibles tels que notamment :<\/p>\r\n    <ul>\r\n      <li>Catastrophes naturelles (ouragans, tremblements de terre, \u00e9ruptions volcaniques, inondations)<\/li>\r\n      <li>\u00c9pid\u00e9mies, pand\u00e9mies, crises sanitaires<\/li>\r\n      <li>Conflits arm\u00e9s, troubles civils, actes de terrorisme<\/li>\r\n      <li>Gr\u00e8ves g\u00e9n\u00e9rales, arr\u00eats de transport<\/li>\r\n      <li>Fermeture de fronti\u00e8res, restrictions gouvernementales<\/li>\r\n    <\/ul>\r\n    <p>\r\n      En cas de force majeure rendant impossible ou manifestement inappropri\u00e9e l'ex\u00e9cution de la\r\n      Prestation, Toucan Discovery fera ses meilleurs efforts pour proposer une solution\r\n      alternative. Dans l'hypoth\u00e8se o\u00f9 aucune solution n'est possible, les sommes vers\u00e9es seront\r\n      rembours\u00e9es sous d\u00e9duction des frais d\u00e9j\u00e0 engag\u00e9s et non r\u00e9cup\u00e9rables aupr\u00e8s de nos\r\n      fournisseurs (h\u00f4tels, compagnies a\u00e9riennes, etc.).\r\n    <\/p>\r\n\r\n    <h2 id=\"responsabilite\">10. Responsabilit\u00e9 et assurance<\/h2>\r\n\r\n    <h3>10.1 Responsabilit\u00e9 de Toucan Discovery<\/h3>\r\n    <p>\r\n      Toucan Discovery s'engage \u00e0 fournir les prestations d\u00e9crites au Devis avec le soin d'un\r\n      professionnel du tourisme r\u00e9ceptif et dans le respect des normes costaricaines et\r\n      internationales applicables.\r\n    <\/p>\r\n    <p>\r\n      Pendant toute la dur\u00e9e du voyage, Toucan Discovery met \u00e0 disposition de ses Voyageurs une\r\n      <strong>ligne d'assistance 24\/7<\/strong> joignable au <strong>+506 8777-7166<\/strong>\r\n      (t\u00e9l\u00e9phone et WhatsApp) pour faire face \u00e0 toute situation impr\u00e9vue.\r\n    <\/p>\r\n    <p>Toucan Discovery ne pourra toutefois \u00eatre tenu responsable :<\/p>\r\n    <ul>\r\n      <li>Des manquements imputables aux Voyageurs (retard, perte de documents, non-respect des consignes de s\u00e9curit\u00e9) ;<\/li>\r\n      <li>Des faits d'un tiers ext\u00e9rieur \u00e0 la fourniture des prestations (compagnie a\u00e9rienne, retards de vols internationaux, etc.) ;<\/li>\r\n      <li>Des cas de force majeure.<\/li>\r\n    <\/ul>\r\n\r\n    <h3>10.2 Assurance voyage<\/h3>\r\n    <div class=\"tdl-alert\">\r\n      <p><strong>Assurance fortement recommand\u00e9e.<\/strong> Nous recommandons vivement \u00e0 tous nos Voyageurs de souscrire avant le d\u00e9part une assurance voyage couvrant au minimum : annulation, rapatriement sanitaire, frais m\u00e9dicaux et hospitalisation, bagages, responsabilit\u00e9 civile.<\/p>\r\n    <\/div>\r\n    <p>\r\n      <strong>Partenaire recommand\u00e9 :<\/strong> pour nos Voyageurs francophones, nous recommandons\r\n      <a href=\"https:\/\/www.chapkadirect.fr\" target=\"_blank\" rel=\"noopener\">Chapka Assurances<\/a>,\r\n      sp\u00e9cialiste des assurances voyages, dont les contrats sont adapt\u00e9s aux s\u00e9jours longue dur\u00e9e\r\n      et aux activit\u00e9s d'aventure propos\u00e9es dans nos programmes. Cette recommandation est indicative\r\n      et n'engage pas le Voyageur, libre de choisir l'assureur de son choix.\r\n    <\/p>\r\n\r\n    <h2 id=\"documents\">11. Documents de voyage<\/h2>\r\n    <p>\r\n      Il appartient au Client de s'assurer qu'il dispose des documents n\u00e9cessaires \u00e0 son voyage :\r\n    <\/p>\r\n    <ul>\r\n      <li><strong>Passeport valide<\/strong> au minimum 6 mois apr\u00e8s la date de retour pr\u00e9vue<\/li>\r\n      <li><strong>Visa<\/strong> selon la nationalit\u00e9 et la destination (le Costa Rica ne requiert pas de visa pour la plupart des nationalit\u00e9s europ\u00e9ennes pour des s\u00e9jours inf\u00e9rieurs \u00e0 90 jours)<\/li>\r\n      <li><strong>Vaccins<\/strong> recommand\u00e9s ou obligatoires selon la destination (\u00e0 v\u00e9rifier aupr\u00e8s de votre m\u00e9decin ou d'un centre de vaccination international)<\/li>\r\n      <li><strong>Billet retour<\/strong> (exigence pour l'entr\u00e9e au Costa Rica)<\/li>\r\n      <li><strong>Preuve d'h\u00e9bergement<\/strong> et\/ou voucher Toucan Discovery (fourni par nos soins)<\/li>\r\n    <\/ul>\r\n    <p>\r\n      Toucan Discovery peut fournir des informations g\u00e9n\u00e9rales \u00e0 ce sujet mais ne peut se\r\n      substituer aux autorit\u00e9s consulaires. Toute impossibilit\u00e9 d'embarquer ou d'entrer dans un\r\n      pays pour d\u00e9faut de documents reste \u00e0 la charge exclusive du Client et ne donne lieu \u00e0\r\n      aucun remboursement.\r\n    <\/p>\r\n\r\n    <h2 id=\"reclamations\">12. R\u00e9clamations<\/h2>\r\n    <p>Toute r\u00e9clamation doit \u00eatre adress\u00e9e par \u00e9crit \u00e0 Toucan Discovery :<\/p>\r\n    <ul>\r\n      <li><strong>Pendant le voyage :<\/strong> signaler imm\u00e9diatement \u00e0 votre contact Toucan via la ligne d'assistance 24\/7 (+506 8777-7166) pour qu'une solution soit recherch\u00e9e sur place en temps r\u00e9el<\/li>\r\n      <li><strong>Apr\u00e8s le voyage :<\/strong> par email \u00e0 <a href=\"mailto:admin@toucandiscovery.com\">admin@toucandiscovery.com<\/a> dans un d\u00e9lai maximum de 30 jours calendaires \u00e0 compter de la date de retour<\/li>\r\n    <\/ul>\r\n    <p>\r\n      Aucune r\u00e9clamation ne pourra \u00eatre trait\u00e9e au-del\u00e0 de ce d\u00e9lai de 30 jours. Toucan Discovery\r\n      s'engage \u00e0 accuser r\u00e9ception de toute r\u00e9clamation sous 48 heures ouvr\u00e9es et \u00e0 y r\u00e9pondre sur\r\n      le fond dans un d\u00e9lai maximum de 30 jours ouvr\u00e9s.\r\n    <\/p>\r\n\r\n    <h2 id=\"donnees\">13. Donn\u00e9es personnelles<\/h2>\r\n    <p>\r\n      Les donn\u00e9es personnelles du Client et des Voyageurs sont trait\u00e9es conform\u00e9ment \u00e0 notre\r\n      <a href=\"\/it\/politique-de-confidentialite\/\">Informativa sulla privacy<\/a>, dans le respect du\r\n      R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD, UE 2016\/679) pour les r\u00e9sidents de\r\n      l'Union europ\u00e9enne et de la loi costaricaine n\u00b08968 sur la protection des donn\u00e9es.\r\n    <\/p>\r\n\r\n    <h2 id=\"juridiction\">14. Droit applicable et juridiction<\/h2>\r\n    <p>\r\n      Les pr\u00e9sentes CGV sont r\u00e9gies par le <strong>droit costaricain<\/strong>, pays du si\u00e8ge\r\n      social de Toucan Discovery S.R.L.\r\n    <\/p>\r\n    <p>\r\n      En cas de litige, les parties s'efforceront en priorit\u00e9 de trouver une solution amiable. \u00c0\r\n      d\u00e9faut de r\u00e8glement amiable dans un d\u00e9lai de 60 jours \u00e0 compter de la notification du litige,\r\n      les tribunaux comp\u00e9tents seront ceux du ressort du si\u00e8ge social de Toucan Discovery \u00e0\r\n      San Jos\u00e9, Costa Rica, sauf disposition l\u00e9gale imp\u00e9rative contraire (notamment les r\u00e8gles de\r\n      protection des consommateurs applicables dans l'Union europ\u00e9enne pour les clients consommateurs\r\n      europ\u00e9ens).\r\n    <\/p>\r\n\r\n    <h2 id=\"contact\">15. Contact<\/h2>\r\n    <div class=\"tdl-info\">\r\n      <p><strong>Toucan Discovery S.R.L.<\/strong><\/p>\r\n      <p>C\u00e9dula Jur\u00eddica : 3-102-862013<\/p>\r\n      <p>San Jos\u00e9, Costa Rica<\/p>\r\n      <p>Email : <a href=\"mailto:admin@toucandiscovery.com\">admin@toucandiscovery.com<\/a><\/p>\r\n      <p>T\u00e9l\u00e9phone \/ Assistance 24\/7 : +506 8777-7166<\/p>\r\n      <p>Web : <a href=\"https:\/\/toucandiscovery.com\/it\/\">www.toucandiscovery.com<\/a><\/p>\r\n    <\/div>\r\n\r\n  <\/main>\r\n\r\n  <!-- CTA -->\r\n  <section class=\"tdl-cta\">\r\n    <h2>Pr\u00eat \u00e0 construire votre voyage sur mesure ?<\/h2>\r\n    <p>Un conseiller Toucan Discovery vous r\u00e9pond sous 24 heures.<\/p>\r\n    <a href=\"\/it\/contact\/\" class=\"tdl-btn\">Richiesta di preventivo<\/a>\r\n  <\/section>\r\n\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Conditions G\u00e9n\u00e9rales de Vente Derni\u00e8re mise \u00e0 jour : 23 avril 2026 Accueil \u203a Conditions G\u00e9n\u00e9rales de Vente Sommaire D\u00e9finitions Acceptation Objet Processus de r\u00e9servation Prix et paiement Annulation par le client Modification par le client Annulation par Toucan Force [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-4534","page","type-page","status-publish","hentry"],"aioseo_notices":[],"acf":[],"_links":{"self":[{"href":"https:\/\/toucandiscovery.com\/it\/wp-json\/wp\/v2\/pages\/4534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toucandiscovery.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/toucandiscovery.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/toucandiscovery.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/toucandiscovery.com\/it\/wp-json\/wp\/v2\/comments?post=4534"}],"version-history":[{"count":7,"href":"https:\/\/toucandiscovery.com\/it\/wp-json\/wp\/v2\/pages\/4534\/revisions"}],"predecessor-version":[{"id":4716,"href":"https:\/\/toucandiscovery.com\/it\/wp-json\/wp\/v2\/pages\/4534\/revisions\/4716"}],"wp:attachment":[{"href":"https:\/\/toucandiscovery.com\/it\/wp-json\/wp\/v2\/media?parent=4534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}